{"id":642,"date":"2023-12-12T01:00:00","date_gmt":"2023-12-12T00:00:00","guid":{"rendered":"https:\/\/www.snowtrex.fr\/magazine\/?p=642"},"modified":"2025-06-26T14:54:02","modified_gmt":"2025-06-26T12:54:02","slug":"biathlon","status":"publish","type":"post","link":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/","title":{"rendered":"10 faits sur le biathlon"},"content":{"rendered":"<p><strong>Le biathlon est l&rsquo;un des sports d&rsquo;hiver les plus connus et les plus populaires au monde. De nombreux fans d&rsquo;hiver sont fascin\u00e9s par ce sport qui allie de mani\u00e8re si unique endurance et pr\u00e9cision et suivent avec attention les comp\u00e9titions au cours desquelles les athl\u00e8tes se surpassent ann\u00e9e apr\u00e8s ann\u00e9e en r\u00e9alisant des performances exceptionnelles. <a href=\"https:\/\/www.snowtrex.fr\/\" target=\"_blank\" rel=\"noopener\">SnowTrex<\/a> a rassembl\u00e9 10 faits concernant le biathlon et montre ce qui enthousiasme tant d&rsquo;amateurs d&rsquo;hiver dans ce sport unique.<\/strong><\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-650 size-Artikelbild_gro\u00df\" title=\"SnowTrex pr\u00e9sente 10 faits sur le biathlon, un sport d'hiver connu et appr\u00e9ci\u00e9.\" src=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-729x486.jpg\" alt=\"SnowTrex pr\u00e9sente 10 faits sur le biathlon, un sport d'hiver connu et appr\u00e9ci\u00e9.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-729x486.jpg 729w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-290x193.jpg 290w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-728x485.jpg 728w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-768x512.jpg 768w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-1536x1024.jpg 1536w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-468x312.jpg 468w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-300x200.jpg 300w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-999x666.jpg 999w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-645x430.jpg 645w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-552x368.jpg 552w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-405x270.jpg 405w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-336x224.jpg 336w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-276x184.jpg 276w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-234x156.jpg 234w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-192x128.jpg 192w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc-120x80.jpg 120w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc.jpg 1920w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"650\">\u00a9 Alexander Rochau\/shutterstock.de<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">SnowTrex pr\u00e9sente 10 faits sur le biathlon, un sport d&rsquo;hiver connu et appr\u00e9ci\u00e9.<\/div>\n         <\/div > \n<p><div class=\"tt-table-of-content\">\n                <span class=\"tt-icon-circle-up tt-table-of-content-button\"><\/span><\/p>\n<div class=\"tt-table-of-content-caption\">\n                    Sommaire\n                <\/div>\n<div class=\"tt-table-of-content-body\">\n                    <a href=\"#1-qu'est-ce-que-le-biathlon-?\"><span class=\"layer-0\">1. Qu&rsquo;est-ce que le biathlon ?<\/span><\/a><a href=\"#2-histoire-du-biathlon\"><span class=\"layer-0\">2. Histoire du biathlon<\/span><\/a><a href=\"#3-les-disciplines-du-biathlon\"><span class=\"layer-0\">3. Les disciplines du biathlon<\/span><\/a><a href=\"#4-l'\u00e9quipement-de-biathlon\"><span class=\"layer-0\">4. L&rsquo;\u00e9quipement de biathlon<\/span><\/a><a href=\"#5-les-comp\u00e9titions-de-biathlon\"><span class=\"layer-0\">5. Les comp\u00e9titions de biathlon<\/span><\/a><a href=\"#6-ski-de-fond\"><span class=\"layer-0\">6. Ski de fond<\/span><\/a><a href=\"#7-le-tir-en-biathlon\"><span class=\"layer-0\">7. Le tir en biathlon<\/span><\/a><a href=\"#8-les-athl\u00e8tes-de-biathlon-c\u00e9l\u00e8bres-et-leurs-records\"><span class=\"layer-0\">8. Les athl\u00e8tes de biathlon c\u00e9l\u00e8bres et leurs records<\/span><\/a><a href=\"#9-dates-de-biathlon\"><span class=\"layer-0\">9. Dates de biathlon<\/span><\/a><a href=\"#10-destinations-populaires-pour-le-biathlon\"><span class=\"layer-0\">10. Destinations populaires pour le biathlon<\/span><\/a><a href=\"#faq-sur-le-biathlon\"><span class=\"layer-0\">FAQ sur le biathlon<\/span><\/a>\n                 <\/div>\n<\/p><\/div>\n<hr>\n<h2 id=\"1-qu'est-ce-que-le-biathlon-?\">1. Qu&rsquo;est-ce que le biathlon ?<\/h2>\n<p>Le biathlon est un sport qui se pratique principalement en hiver et qui trouve son origine dans la chasse. Le terme \u00ab\u00a0biathlon\u00a0\u00bb vient du grec et signifie \u00ab\u00a0duel\u00a0\u00bb. Le \u00ab\u00a0deux\u00a0\u00bb ne se r\u00e9f\u00e8re pas aux athl\u00e8tes, mais aux deux disciplines pratiqu\u00e9es : le ski de fond et le tir. Le biathlon combine ainsi une discipline d&rsquo;endurance avec une discipline de pr\u00e9cision et exige des sportifs un \u00e9ventail particulier de comp\u00e9tences gr\u00e2ce \u00e0 cette combinaison unique.<\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-651 size-Artikelbild_gro\u00df\" title=\"Le terme &quot;biathlon&quot; signifie &quot;duel&quot; et vient du grec.\" src=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-729x486.jpg\" alt=\"Le terme &quot;biathlon&quot; signifie &quot;duel&quot; et vient du grec.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-729x486.jpg 729w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-290x193.jpg 290w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-728x485.jpg 728w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-768x512.jpg 768w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-468x312.jpg 468w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-300x200.jpg 300w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-999x666.jpg 999w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-645x430.jpg 645w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-552x368.jpg 552w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-405x270.jpg 405w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-336x224.jpg 336w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-276x184.jpg 276w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-234x156.jpg 234w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-192x128.jpg 192w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr-120x80.jpg 120w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21520_shutterstock_1225030600-scr.jpg 1440w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"651\">\u00a9 Alexander Rochau\/shutterstock.de<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">Le terme \u00ab\u00a0biathlon\u00a0\u00bb signifie \u00ab\u00a0duel\u00a0\u00bb et vient du grec.<\/div>\n         <\/div > \n<h2 id=\"2-histoire-du-biathlon\">2. Histoire du biathlon<\/h2>\n<p>Le biathlon s&rsquo;est d\u00e9velopp\u00e9 sur des milliers d&rsquo;ann\u00e9es. Des peintures rupestres norv\u00e9giennes indiquent qu&rsquo;il y a plus de 5000 ans, les hommes utilisaient d\u00e9j\u00e0 les skis comme un outil pour poursuivre les animaux sauvages dans la neige. Une illustration datant de 1050 apr\u00e8s J.-C. montre un homme chassant \u00e0 ski avec un arc et des fl\u00e8ches, ce qui peut \u00eatre interpr\u00e9t\u00e9 comme le pr\u00e9curseur du biathlon actuel.<\/p>\n<p>L&rsquo;origine du biathlon actuel, qui combine le tir \u00e0 la carabine et le ski de fond, se situe dans le domaine militaire. Pendant des si\u00e8cles, ce sport s&rsquo;est r\u00e9pandu \u00e0 partir des militaires norv\u00e9giens et russes dans tous les pays qui devaient faire face \u00e0 une neige abondante en hiver.<\/p>\n<p>Apr\u00e8s la Seconde Guerre mondiale, le sport combin\u00e9 a \u00e9t\u00e9 d\u00e9militaris\u00e9 et le biathlon a \u00e9t\u00e9 de plus en plus accept\u00e9 et encourag\u00e9 en tant que sport civil. En 1954, le Comit\u00e9 international olympique a reconnu le biathlon comme un sport \u00e0 part enti\u00e8re et, en 1958, les premiers championnats du monde ont \u00e9t\u00e9 organis\u00e9s \u00e0 Saalfelden, en Autriche. Le biathlon est entr\u00e9 dans l&rsquo;histoire olympique en 1960 dans la station de ski de Palisades Tahoe. \u00c0 l&rsquo;\u00e9poque, le domaine skiable s&rsquo;appelait encore Squaw Valley Ski Resort. Jusqu&rsquo;alors, les comp\u00e9titions n&rsquo;\u00e9taient organis\u00e9es que pour les hommes et ce n&rsquo;est qu&rsquo;en 1981 que la premi\u00e8re comp\u00e9tition internationale f\u00e9minine a eu lieu \u00e0 J\u00e1chymov, alors en Tch\u00e9coslovaquie. Les premiers championnats du monde de biathlon pour femmes ont \u00e9t\u00e9 organis\u00e9s en 1984, \u00e0 l&rsquo;\u00e9poque s\u00e9par\u00e9ment des hommes. Depuis 1989, les championnats du monde se d\u00e9roulent \u00e0 une date unique, sans distinction de sexe. En outre, depuis 1992 \u00e0 Albertville, le biathlon est \u00e9galement une discipline olympique chez les femmes.<\/p>\n<p>Aujourd&rsquo;hui, le biathlon est l&rsquo;un des sports d&rsquo;hiver les plus connus et est consid\u00e9r\u00e9 comme le troisi\u00e8me sport t\u00e9l\u00e9vis\u00e9 le plus populaire en Allemagne, apr\u00e8s le football et la formule 1. Cela s&rsquo;explique notamment par la combinaison du ski de fond et du tir, qui rend ce sport d&rsquo;hiver si unique et maintient le suspense jusqu&rsquo;\u00e0 la fin de la course. De plus, les athl\u00e8tes qui brillent en hiver avec de nouveaux records et des victoires spectaculaires tout en continuant \u00e0 \u00e9crire l&rsquo;histoire du biathlon fascinent bien s\u00fbr aussi.<\/p>\n<h2 id=\"3-les-disciplines-du-biathlon\">3. Les disciplines du biathlon<\/h2>\n<p>Il existe diff\u00e9rentes disciplines dans le biathlon, qui suivent toutes le m\u00eame principe de base, \u00e0 savoir la combinaison du ski de fond et du tir. Les disciplines du biathlon se distinguent les unes des autres par des r\u00e8gles, des distances et un nombre de participants diff\u00e9rents. Actuellement, ces sept disciplines sont disput\u00e9es lors de la Coupe du monde de biathlon et des Championnats du monde : l&rsquo;individuel, le sprint, la poursuite, le d\u00e9part en ligne, le relais, le relais mixte et le relais mixte individuel. Lors des Jeux olympiques, les m\u00eames disciplines sont au programme, \u00e0 l&rsquo;exception du relais mixte simple.<\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-652 size-Artikelbild_gro\u00df\" title=\"Toutes les disciplines du biathlon suivent le m\u00eame principe de base avec la combinaison du ski de fond et du tir.\" src=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-729x486.jpg\" alt=\"Toutes les disciplines du biathlon suivent le m\u00eame principe de base avec la combinaison du ski de fond et du tir.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-729x486.jpg 729w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-290x193.jpg 290w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-728x485.jpg 728w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-768x511.jpg 768w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-468x312.jpg 468w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-300x200.jpg 300w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-999x666.jpg 999w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-645x430.jpg 645w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-552x368.jpg 552w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-405x270.jpg 405w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-336x224.jpg 336w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-276x184.jpg 276w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-234x156.jpg 234w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-192x128.jpg 192w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr-120x80.jpg 120w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14854_shutterstock_754299328-bearbeitet-scr.jpg 1440w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"652\">\u00a9 Carlos Charlez\/shutterstock.de<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">Toutes les disciplines du biathlon suivent le m\u00eame principe de base avec la combinaison du ski de fond et du tir.<\/div>\n         <\/div > \n<h2 id=\"4-l'\u00e9quipement-de-biathlon\">4. L&rsquo;\u00e9quipement de biathlon<\/h2>\n<p>L&rsquo;\u00e9quipement d&rsquo;un biathl\u00e8te comprend de nombreux objets sp\u00e9cifiques. Les \u00e9l\u00e9ments de base sont la combinaison, les lunettes de ski ad\u00e9quates, les gants chauds et un bonnet pour prot\u00e9ger les oreilles. Bien entendu, le fusil, les skis et les b\u00e2tons de ski appropri\u00e9s sont \u00e9galement indispensables.<\/p>\n<p>Le premier \u00e9l\u00e9ment principal de l&rsquo;\u00e9quipement de biathlon est l&rsquo;\u00e9quipement n\u00e9cessaire \u00e0 la pratique du ski de fond. Le ski de fond en fait bien s\u00fbr partie. Comme les athl\u00e8tes utilisent en priorit\u00e9 la technique du skating, il s&rsquo;agit g\u00e9n\u00e9ralement d&rsquo;un ski de skating d&rsquo;environ 1,2 kg et d&rsquo;environ 5 cm de large. La longueur du ski d\u00e9pend de la taille de l&rsquo;athl\u00e8te et n&rsquo;est pas limit\u00e9e. Un autre \u00e9l\u00e9ment important de l&rsquo;\u00e9quipement est constitu\u00e9 par les chaussures de ski de fond, qui sont fix\u00e9es par une fixation \u00e0 peu pr\u00e8s au milieu du ski. Pour que les athl\u00e8tes aient une meilleure pouss\u00e9e, ils peuvent d\u00e9coller l&rsquo;arri\u00e8re de la chaussure du ski \u00e0 chaque pas. Les skis et les chaussures sont compl\u00e9t\u00e9s par des b\u00e2tons de ski de fond. Mesur\u00e9s \u00e0 la hauteur des \u00e9paules du biathl\u00e8te, ces derniers garantissent que les athl\u00e8tes puissent se pousser de mani\u00e8re optimale dans la neige.<\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-653 size-Artikelbild_gro\u00df\" title=\"Les skis de fond des biathl\u00e8tes p\u00e8sent en g\u00e9n\u00e9ral environ 1,2 kg et mesurent environ 5 cm de large.\" src=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-729x486.jpg\" alt=\"Les skis de fond des biathl\u00e8tes p\u00e8sent en g\u00e9n\u00e9ral environ 1,2 kg et mesurent environ 5 cm de large.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-729x486.jpg 729w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-290x193.jpg 290w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-728x485.jpg 728w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-768x512.jpg 768w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-468x312.jpg 468w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-300x200.jpg 300w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-999x666.jpg 999w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-645x430.jpg 645w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-552x368.jpg 552w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-405x270.jpg 405w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-336x224.jpg 336w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-276x184.jpg 276w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-234x156.jpg 234w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-192x128.jpg 192w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr-120x80.jpg 120w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS16339_shutterstock_557009656-scr.jpg 1440w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"653\">\u00a9 VektorSport\/shutterstock.de<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">Les skis de fond des biathl\u00e8tes p\u00e8sent en g\u00e9n\u00e9ral environ 1,2 kg et mesurent environ 5 cm de large.<\/div>\n         <\/div > \n<p>Le deuxi\u00e8me \u00e9l\u00e9ment principal de l&rsquo;\u00e9quipement est le fusil, pour lequel les athl\u00e8tes ont besoin d&rsquo;un permis de port d&rsquo;armes. Il est sp\u00e9cifi\u00e9 que la carabine doit \u00eatre de petit calibre et peser entre 3,8 et 4,5 kg. Les fusils sont d&rsquo;ailleurs contr\u00f4l\u00e9s par les juges avant chaque comp\u00e9tition &#8230; la s\u00e9curit\u00e9 avant tout. Les athl\u00e8tes b\u00e9n\u00e9ficient d&rsquo;une certaine marge de manoeuvre concernant certains d\u00e9tails de la carabine. Ils peuvent notamment choisir la taille, le mat\u00e9riau et la texture de la crosse et faire installer des compartiments pour les outils ou les munitions de rechange dans leurs carabines.<\/p>\n<p>Les munitions sont \u00e9galement soumises \u00e0 certaines exigences. Les projectiles doivent par exemple avoir un calibre de .22 lr (5,6 mm). En outre, le poids du projectile doit \u00eatre compris entre 2,55 et 2,75 grammes et la vitesse maximale de la bouche doit \u00eatre de 360 m\/s. La munition est d&rsquo;ailleurs sp\u00e9cialement adapt\u00e9e \u00e0 une utilisation \u00e0 basse temp\u00e9rature.<\/p>\n<p>Les biathl\u00e8tes ont donc, en plus de leurs v\u00eatements et de leur \u00e9quipement de ski de fond, un fusil d&rsquo;environ 4 kg qu&rsquo;ils doivent transporter, munitions comprises, dans un syst\u00e8me de portage sur le dos pendant la comp\u00e9tition.<\/p>\n<h2 id=\"5-les-comp\u00e9titions-de-biathlon\">5. Les comp\u00e9titions de biathlon<\/h2>\n<p>Il existe de nombreuses comp\u00e9titions de biathlon pour diff\u00e9rentes cat\u00e9gories d&rsquo;\u00e2ge et diff\u00e9rents niveaux de performance. Les comp\u00e9titions les plus connues sont les comp\u00e9titions internationales des femmes et des hommes professionnels. Il s&rsquo;agit des Jeux olympiques d&rsquo;hiver, des Championnats du monde de biathlon et de la Coupe du monde de biathlon.<\/p>\n<p>La Coupe du monde de biathlon est la plus haute cat\u00e9gorie de comp\u00e9tition en biathlon et s&rsquo;\u00e9tend sur tout un hiver. La Coupe du monde se d\u00e9roule g\u00e9n\u00e9ralement dans neuf stations de Coupe du monde, dont les courses sont organis\u00e9es par la F\u00e9d\u00e9ration internationale de biathlon (IBU). Lors de chaque course, les athl\u00e8tes essaient d&rsquo;accumuler des points de Coupe du monde. \u00c0 la fin de la saison, tous les points sont additionn\u00e9s et le biathl\u00e8te ou la biathl\u00e8te ayant obtenu le plus de points de Coupe du monde remporte le classement g\u00e9n\u00e9ral de la Coupe du monde. En outre, depuis 1989, il existe \u00e9galement un classement dans les disciplines individuelles, qui d\u00e9termine le vainqueur de la saison dans chaque discipline.<\/p>\n<p>A la fin de la s\u00e9rie de comp\u00e9titions qui vient de s&rsquo;achever, la F\u00e9d\u00e9ration internationale a pr\u00e9sent\u00e9 ici les meilleures images de la saison :<\/p>\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"lyte-wrapper\" title=\"World Cup 21\/22: the Beauty of Biathlon\" style=\"width:853px;max-width:100%;margin:5px auto;\"><div class=\"lyMe\" id=\"WYL_Rk9YBUW2g6c\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/www.snowtrex.fr\/magazine\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FRk9YBUW2g6c%2Fhqdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/Rk9YBUW2g6c\" \/><meta itemprop=\"duration\" content=\"PT3M4S\" \/><meta itemprop=\"uploadDate\" content=\"2022-03-31T17:15:10Z\" \/><\/div><div id=\"lyte_Rk9YBUW2g6c\" data-src=\"https:\/\/www.snowtrex.fr\/magazine\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FRk9YBUW2g6c%2Fhqdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">World Cup 21\/22: the Beauty of Biathlon<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"http:\/\/youtu.be\/Rk9YBUW2g6c\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.snowtrex.fr\/magazine\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=http%3A%2F%2Fi.ytimg.com%2Fvi%2FRk9YBUW2g6c%2F0.jpg\" alt=\"World Cup 21\/22: the Beauty of Biathlon\" width=\"853\" height=\"460\" \/><br \/>Lire cette vid\u00e9o sur YouTube<\/a><\/noscript><meta itemprop=\"description\" content=\"What makes biathlon our favourite sport? We tried to show all the reasons why with this clip featuring some of the most aesthetically beautiful shots from the BMW IBU World Cup 2021\/2022 season.\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:853px;margin:5px auto;\"><br\/><span class=\"lyte_disclaimer\">Please also note that by using our services and integrating the YouTube API Services, the <a href=\"https:\/\/www.youtube.com\/t\/terms\">YouTube Terms of Service<\/a> and the <a href=\"https:\/\/developers.google.com\/youtube\/terms\/api-services-terms-of-service-emea\">YouTube API Services Terms<\/a> apply and your use of our website is deemed to be acceptance of these terms.<\/span><\/div><figcaption><\/figcaption><\/figure>\n<p>Le biathlon fait partie du programme olympique officiel depuis 1960, date \u00e0 laquelle une course de 20 km a \u00e9t\u00e9 organis\u00e9e, et depuis, les \u00e9preuves de biathlon sont organis\u00e9es tous les quatre ans lors des Jeux olympiques d&rsquo;hiver. En 2018, \u00e0 Pyeongchang, 33 m\u00e9dailles ont \u00e9t\u00e9 attribu\u00e9es au cours de onze \u00e9preuves de diff\u00e9rentes disciplines, ce qui fait du biathlon l&rsquo;un des sports olympiques comptant le plus grand nombre d&rsquo;\u00e9preuves.<\/p>\n<p>Toutes les ann\u00e9es non olympiques, les championnats du monde de biathlon sont organis\u00e9s pour les hommes depuis 1958 et pour les femmes depuis 1984. Les \u00e9preuves des championnats du monde se d\u00e9roulent g\u00e9n\u00e9ralement sur deux semaines en f\u00e9vrier ou en mars et font partie de la Coupe du monde de biathlon.<\/p>\n<h2 id=\"6-ski-de-fond\">6. Ski de fond<\/h2>\n<p>La premi\u00e8re discipline du sport combin\u00e9 qu&rsquo;est le biathlon est le ski de fond. Les biathl\u00e8tes ont, selon la discipline, entre 3 et 20 km de parcours qu&rsquo;ils doivent parcourir en une seule course avec une technique de ski optimis\u00e9e. Dans ce contexte, la technique du skating s&rsquo;est \u00e9tablie depuis les ann\u00e9es 1980 et est aujourd&rsquo;hui presque exclusivement utilis\u00e9e.<\/p>\n<p>Dans cette technique, les athl\u00e8tes se poussent du sol avec un ski et les b\u00e2tons et glissent vers l&rsquo;avant sur l&rsquo;autre ski &#8211; comme en patin en ligne ou en patin \u00e0 glace. Selon les conditions du parcours et la situation de la comp\u00e9tition, les sportifs utilisent quatre techniques ou rythmes de base de la technique de skating : 2-1-court, 2-1-long, 1-1 et une technique sans b\u00e2tons. Mais que signifient exactement les d\u00e9signations des techniques ? Voici un exemple d&rsquo;explication de la technique 2-1-court : dans la technique 2-1-court, \u00e9galement appel\u00e9e technique du bras guide ou pas de montagne, le \u00ab\u00a02-1\u00a0\u00bb se r\u00e9f\u00e8re \u00e0 deux pouss\u00e9es de jambes, soutenues par une seule pouss\u00e9e de double b\u00e2ton avec les bras. Cette technique est relativement lente, mais particuli\u00e8rement efficace sur les terrains en forte pente. Le \u00ab\u00a0court\u00a0\u00bb se r\u00e9f\u00e8re \u00e0 la phase de glisse assez courte sur un terrain en pente.<\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-654 size-Artikelbild_gro\u00df\" title=\"En ski de fond, les biathl\u00e8tes utilisent la technique du skating.\" src=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-729x486.jpg\" alt=\"En ski de fond, les biathl\u00e8tes utilisent la technique du skating.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-729x486.jpg 729w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-290x193.jpg 290w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-728x485.jpg 728w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-768x511.jpg 768w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-468x312.jpg 468w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-300x200.jpg 300w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-999x666.jpg 999w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-645x430.jpg 645w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-552x368.jpg 552w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-405x270.jpg 405w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-336x224.jpg 336w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-276x184.jpg 276w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-234x156.jpg 234w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-192x128.jpg 192w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr-120x80.jpg 120w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS14853_shutterstock_754299325-scr.jpg 1440w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"654\">\u00a9 Carlos Charlez\/shutterstock.de<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">En ski de fond, les biathl\u00e8tes utilisent la technique du skating.<\/div>\n         <\/div > \n<p>Les quatre rythmes sont extr\u00eamement exigeants et sollicitent presque tous les muscles du corps. Seuls les meilleurs athl\u00e8tes de ce sport parviennent, entre les efforts d&rsquo;endurance pendant les courtes phases au stand de tir, \u00e0 contr\u00f4ler leur corps de mani\u00e8re \u00e0 permettre un tir pr\u00e9cis.<\/p>\n<h2 id=\"7-le-tir-en-biathlon\">7. Le tir en biathlon<\/h2>\n<p>Le tir est la discipline de pr\u00e9cision du biathlon, dans laquelle les athl\u00e8tes doivent \u00eatre particuli\u00e8rement concentr\u00e9s et focalis\u00e9s.<\/p>\n<p>Selon la discipline, on tire au moins une fois en position couch\u00e9e et une fois en position debout. Sur le pas de tir, il y a 30 lignes de tir, parmi lesquelles les athl\u00e8tes peuvent en choisir une pendant la comp\u00e9tition, \u00e0 moins que l&rsquo;ordre de la comp\u00e9tition ne soit fix\u00e9. Il y a cinq cibles, situ\u00e9es exactement \u00e0 50 m\u00e8tres des athl\u00e8tes, dont le diam\u00e8tre est de 4,5 cm (tir couch\u00e9) ou de 11,5 cm (tir debout), selon la position de l&rsquo;athl\u00e8te. Si le biathl\u00e8te tire et touche, une cible noire se d\u00e9place devant la cible blanche. Si l&rsquo;athl\u00e8te ne touche pas la cible, il doit effectuer un tour de p\u00e9nalit\u00e9 de 150 m ou 75 m par tir manqu\u00e9, selon la discipline du biathlon, ou une minute de p\u00e9nalit\u00e9 lui est attribu\u00e9e.<\/p>\n<p>L&rsquo;objectif de chaque biathl\u00e8te est de toucher rapidement les cinq cibles lors du tir afin de perdre le moins de temps possible et de pouvoir repartir imm\u00e9diatement sur la piste de ski de fond.<\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-655 size-Artikelbild_gro\u00df\" title=\"Lors du tir, les biathl\u00e8tes doivent \u00eatre particuli\u00e8rement concentr\u00e9s.\" src=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-729x486.jpg\" alt=\"Lors du tir, les biathl\u00e8tes doivent \u00eatre particuli\u00e8rement concentr\u00e9s.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-729x486.jpg 729w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-290x194.jpg 290w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-728x486.jpg 728w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-768x513.jpg 768w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-468x312.jpg 468w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-727x486.jpg 727w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-300x200.jpg 300w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-999x666.jpg 999w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-645x430.jpg 645w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-552x368.jpg 552w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-405x270.jpg 405w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-336x224.jpg 336w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-276x184.jpg 276w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-234x156.jpg 234w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-192x128.jpg 192w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr-120x80.jpg 120w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21528_shutterstock_1243929145-scr.jpg 1440w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"655\">\u00a9 Alexander Rochau\/shutterstock.de<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">Lors du tir, les biathl\u00e8tes doivent \u00eatre particuli\u00e8rement concentr\u00e9s.<\/div>\n         <\/div > \n<h2 id=\"8-les-athl\u00e8tes-de-biathlon-c\u00e9l\u00e8bres-et-leurs-records\">8. Les athl\u00e8tes de biathlon c\u00e9l\u00e8bres et leurs records<\/h2>\n<p>Les athl\u00e8tes les plus c\u00e9l\u00e8bres du biathlon sont principalement les biathl\u00e8tes et les biathl\u00e8tes f\u00e9minines qui ont remport\u00e9 le plus de succ\u00e8s et de m\u00e9dailles. Comme les biathl\u00e8tes concourent principalement dans plusieurs, et souvent m\u00eame dans toutes les disciplines de leur sport, les records les plus reconnus sont ceux qui repr\u00e9sentent le plus grand nombre de m\u00e9dailles d&rsquo;or dans l&rsquo;une des trois grandes comp\u00e9titions.<\/p>\n<p>Le Norv\u00e9gien Ole Einar Bj\u00f8rndalen est consid\u00e9r\u00e9 comme le biathl\u00e8te le plus titr\u00e9 de tous les temps. Pendant plus de 25 ans, il a particip\u00e9 \u00e0 des comp\u00e9titions internationales de biathlon. Au cours de cette p\u00e9riode, il a jou\u00e9 en t\u00eate des comp\u00e9titions professionnelles pendant pas moins de 20 ans. Cette c\u00e9l\u00e9brit\u00e9 a remport\u00e9 huit m\u00e9dailles d&rsquo;or aux Jeux olympiques d&rsquo;hiver et 20 m\u00e9dailles d&rsquo;or aux championnats du monde. Bj\u00f8rndalen est ainsi entr\u00e9 dans l&rsquo;histoire en tant que d\u00e9tenteur du record du plus grand nombre de m\u00e9dailles d&rsquo;or dans deux des plus importantes comp\u00e9titions de biathlon.<\/p>\n<p>Martin Fourcade est \u00e9galement devenu une c\u00e9l\u00e9brit\u00e9 du biathlon apr\u00e8s avoir brill\u00e9 pendant plus de dix ans par ses performances exceptionnelles. Il a \u00e9t\u00e9 le premier biathl\u00e8te \u00e0 remporter le classement g\u00e9n\u00e9ral de la Coupe du monde sept fois de suite. En outre, le Fran\u00e7ais a remport\u00e9 15 autres m\u00e9dailles aux championnats du monde et s&rsquo;est hiss\u00e9 sur sept podiums olympiques.<\/p>\n<p>Magdalena Neuner est une biathl\u00e8te c\u00e9l\u00e8bre et tr\u00e8s performante. Elle a particip\u00e9 aux comp\u00e9titions de biathlon professionnel entre 2006 et 2012 et a pu f\u00eater un total de 47 victoires en Coupe du monde durant cette p\u00e9riode. De plus, l&rsquo;Allemande a remport\u00e9 deux fois l&rsquo;or aux Jeux olympiques et s&rsquo;est assur\u00e9e le record f\u00e9minin du plus grand nombre de titres de championne du monde avec un total de douze m\u00e9dailles d&rsquo;or.<\/p>\n<p>Deux autres ic\u00f4nes du biathlon sont les biathl\u00e8tes Darja Domratschewa et Magdalena Forsberg. La premi\u00e8re est l&rsquo;\u00e9pouse d&rsquo;Ole Einar Bj\u00f8rndalen et d\u00e9tient, comme son mari, le record du plus grand nombre de m\u00e9dailles d&rsquo;or remport\u00e9es par une biathl\u00e8te aux Jeux olympiques. Entre 2014 et 2018, la Bi\u00e9lorusse a remport\u00e9 la palme d&rsquo;or en individuel, en poursuite, en mass start et en relais. Magdalena Forsberg est la troisi\u00e8me femme \u00e0 d\u00e9tenir le record du plus grand nombre de m\u00e9dailles d&rsquo;or dans l&rsquo;une des trois \u00e9preuves majeures. La Su\u00e9doise a \u00e9t\u00e9 l&rsquo;athl\u00e8te dominante de la discipline entre 1997 et 2002. Durant cette p\u00e9riode, elle a pu \u00e9tablir le record incontest\u00e9 de six victoires cons\u00e9cutives au classement g\u00e9n\u00e9ral de la Coupe du monde chez les femmes. De plus, elle a \u00e9t\u00e9 six fois championne du monde et a pu ramener deux fois la m\u00e9daille de bronze aux Jeux olympiques d&rsquo;hiver de 2002 \u00e0 Salt Lake City.<\/p>\n<p>D&rsquo;autres noms qu&rsquo;un fan du monde du biathlon allemand devrait avoir entendus : Laura Dahlmeier, Arnd Pfeiffer, Erik Lesser, Marina Glagow, Kati Wilhelm, Andrea Henkel, Uschi Disl, Frank Ullrich, Ricco Gro\u00df, Rapha\u00ebl Poir\u00e9e, Sven Fischer, Michael Greis, Peter Angerer.<\/p>\n<h2 id=\"9-dates-de-biathlon\">9. Dates de biathlon<\/h2>\n<p>Les comp\u00e9titions de biathlon ont toutes lieu pendant la saison d&rsquo;hiver. En fonction des comp\u00e9titions qui se d\u00e9roulent au cours d&rsquo;une saison, l&rsquo;Union internationale de biathlon (IBU) fixe les dates et les lieux des championnats du monde et de la Coupe du monde.<\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-656 size-Artikelbild_gro\u00df\" title=\"Les stations de sports d'hiver allemandes d'Oberhof et de Ruhpolding ont \u00e9galement \u00e9t\u00e9 choisies presque chaque ann\u00e9e par l'IBU pour accueillir une coupe du monde au cours des derni\u00e8res d\u00e9cennies.\" src=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-729x486.jpg\" alt=\"Les stations de sports d'hiver allemandes d'Oberhof et de Ruhpolding ont \u00e9galement \u00e9t\u00e9 choisies presque chaque ann\u00e9e par l'IBU pour accueillir une coupe du monde au cours des derni\u00e8res d\u00e9cennies.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-729x486.jpg 729w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-290x193.jpg 290w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-728x484.jpg 728w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-468x312.jpg 468w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-300x200.jpg 300w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-999x666.jpg 999w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-645x430.jpg 645w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-552x368.jpg 552w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-405x270.jpg 405w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-336x224.jpg 336w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-276x184.jpg 276w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-234x156.jpg 234w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-192x128.jpg 192w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS4894_shutterstock_303280229-scr-120x80.jpg 120w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"656\">\u00a9 canadastock\/shutterstock.de<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">Les stations de sports d&rsquo;hiver allemandes d&rsquo;Oberhof et de Ruhpolding ont \u00e9galement \u00e9t\u00e9 choisies presque chaque ann\u00e9e par l&rsquo;IBU pour accueillir une coupe du monde au cours des derni\u00e8res d\u00e9cennies.<\/div>\n         <\/div > \n<p>Pour la Coupe du monde, un total de 22 courses individuelles et quatre courses pour chaque relais doivent \u00eatre organis\u00e9es par saison entre fin novembre et fin mars. Les courses sont organis\u00e9es dans neuf stations de Coupe du monde diff\u00e9rentes. Pour toutes les ann\u00e9es non olympiques, les Championnats du monde, qui se d\u00e9roulent sur deux semaines en f\u00e9vrier ou en mars, constituent \u00e9galement une station de la Coupe du monde.<\/p>\n<p>Dans le cadre des Jeux olympiques d&rsquo;hiver, les comp\u00e9titions de biathlon se d\u00e9roulent tous les quatre ans en f\u00e9vrier.<\/p>\n<h2 id=\"10-destinations-populaires-pour-le-biathlon\">10. Destinations populaires pour le biathlon<\/h2>\n<p>De nombreuses stations de ski dans les Alpes disposent de pistes de ski de fond sur lesquelles les amateurs d&rsquo;hiver peuvent s&rsquo;entra\u00eener \u00e0 la partie ski de fond du biathlon dans le cadre d&rsquo;un cours ou seuls. De nombreuses r\u00e9gions comme la <a href=\"https:\/\/www.snowtrex.fr\/autriche\/olympiaregion_seefeld\/sejour_ski.html\" target=\"_blank\" rel=\"noopener\">r\u00e9gion olympique autrichienne de Seefeld<\/a>, la r\u00e9gion Auvergne-Rh\u00f4ne-Alpes en France, <a href=\"https:\/\/www.snowtrex.fr\/suisse\/engadin\/sejour-ski.html\" target=\"_blank\" rel=\"noopener\">l&rsquo;Engadine<\/a> en Suisse et la <a href=\"https:\/\/www.snowtrex.fr\/allemagne\/oberhof\/sejour-ski.html\" target=\"_blank\" rel=\"noopener\">r\u00e9gion touristique d&rsquo;Oberhof<\/a> en Allemagne sont de v\u00e9ritables bastions du ski de fond. Le paradis absolu du ski de fond dans les Alpes est d\u00e9finitivement la r\u00e9gion des <a href=\"https:\/\/www.snowtrex.fr\/univers-de-vacances\/dolomiti-superski.html\" target=\"_blank\" rel=\"noopener\">Dolomites<\/a> italiennes avec pas moins de 1 300 kilom\u00e8tres de pistes.<\/p>\n<div class=\"tt-post-image-wrapper tt-post-image-wrapper-full\">\n            <div class=\"tt-image-copyright-container\">\n                <a href=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr.jpg\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" data-wrapped=\"true\" class=\"wp-image-657 size-Artikelbild_gro\u00df\" title=\"En Engadine, en Suisse, les skieurs de fond se sentent parfaitement \u00e0 l'aise.\" src=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-729x486.jpg\" alt=\"En Engadine, en Suisse, les skieurs de fond se sentent parfaitement \u00e0 l'aise.\" width=\"729\" height=\"486\" srcset=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-729x486.jpg 729w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-468x312.jpg 468w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-300x200.jpg 300w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-999x666.jpg 999w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-645x430.jpg 645w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-552x368.jpg 552w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-405x270.jpg 405w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-336x224.jpg 336w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-276x184.jpg 276w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-234x156.jpg 234w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-192x128.jpg 192w, https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS15198_2018-02-10-122158-13-scr-120x80.jpg 120w\" sizes=\"(min-width: 1009px) 729px, (min-width: 819px) 594px, (min-width: 569px) 729px, (min-width: 449px) 468px, 348px\" \/><\/a><div class=\"tt-image-copyright\" data-image-id=\"657\">\u00a9 TravelTrex<\/div>\n            <\/div>\n            <div class=\"tt-post-caption\">En Engadine, en Suisse, les skieurs de fond se sentent parfaitement \u00e0 l&rsquo;aise.<\/div>\n         <\/div > \n<p>Le tir est bien s\u00fbr aussi tr\u00e8s attrayant pour les biathl\u00e8tes amateurs. Celui-ci ne peut \u00eatre pratiqu\u00e9 que sur des stands de tir, qui se trouvent g\u00e9n\u00e9ralement dans des stades de biathlon. Pour les d\u00e9butants, il existe des ateliers au cours desquels des biathl\u00e8tes exp\u00e9riment\u00e9s leur enseignent les bases de ce sport combin\u00e9. Des ateliers de biathlon sont notamment propos\u00e9s dans des paradis hivernaux comme <a href=\"https:\/\/www.snowtrex.fr\/allemagne\/garmisch-partenkirchen\/sejour-ski.html\" target=\"_blank\" rel=\"noopener\">Garmisch-Partenkirchen<\/a> en Bavi\u00e8re, <a href=\"https:\/\/www.snowtrex.fr\/allemagne\/oberhof\/sejour-ski.html\" target=\"_blank\" rel=\"noopener\">Oberhof<\/a> en Thuringe, <a href=\"https:\/\/www.snowtrex.fr\/autriche\/hochfilzen\/sejour-ski.html\" target=\"_blank\" rel=\"noopener\">Hochfilzen<\/a> en Autriche et la station de ski <a href=\"https:\/\/www.snowtrex.fr\/suisse\/arosa\/domaine-skiable.html\" target=\"_blank\" rel=\"noopener\">d&rsquo;Arosa-Lenzerheide<\/a> en Suisse.<\/p>\n<p>Les amateurs d&rsquo;hiver curieux et les biathl\u00e8tes amateurs exp\u00e9riment\u00e9s ont donc un large choix de destinations o\u00f9 ils peuvent essayer, pratiquer, s&rsquo;entra\u00eener et perfectionner leurs comp\u00e9tences en biathlon.<\/p>\n<h2 id=\"faq-sur-le-biathlon\">FAQ sur le biathlon<\/h2>\n<h3>Qu\u2019est-ce que le biathlon ?<\/h3>\n<p>Le biathlon est un sport d\u2019hiver qui se compose du ski de fond et du tir. Ce sport combine endurance et pr\u00e9cision dans sept disciplines diff\u00e9rentes et exige des athl\u00e8tes un \u00e9ventail particulier de comp\u00e9tences.<\/p>\n<h3>D\u2019o\u00f9 vient le terme \u00ab biathlon \u00bb ?<\/h3>\n<p>Le terme \u00ab biathlon \u00bb vient du grec et se traduit par \u00ab duel \u00bb. Le \u00ab deux \u00bb se r\u00e9f\u00e8re aux deux disciplines pratiqu\u00e9es : le ski de fond et le tir.<\/p>\n<h3>Quand ont eu lieu les premiers championnats du monde de biathlon ?<\/h3>\n<p>Les premiers championnats du monde de biathlon masculin ont \u00e9t\u00e9 organis\u00e9s en 1958 \u00e0 Saalfelden, en Autriche. Les femmes ont pu participer pour la premi\u00e8re fois \u00e0 un championnat du monde de biathlon en 1984 \u00e0 Chamonix. Depuis 1989, les championnats du monde sont organis\u00e9s simultan\u00e9ment et sans distinction de sexe.<\/p>\n<h3>Quand le biathlon est-il devenu une discipline olympique ?<\/h3>\n<p>Le biathlon a \u00e9t\u00e9 reconnu comme un sport \u00e0 part enti\u00e8re par le Comit\u00e9 international olympique en 1954. Ce sport a \u00e9t\u00e9 inscrit pour la premi\u00e8re fois au programme des Jeux olympiques d\u2019hiver de Squaw Valley en 1960. Les femmes ont pu prendre part pour la premi\u00e8re fois \u00e0 des \u00e9preuves olympiques de biathlon en 1992 \u00e0 Albertville.<\/p>\n<h3>Quelles sont les disciplines du biathlon ?<\/h3>\n<p>Sept disciplines sont actuellement disput\u00e9es dans le cadre de la Coupe du monde et des Championnats du monde de biathlon : l\u2019individuel, le sprint, la poursuite, le d\u00e9part en ligne, le relais, le relais mixte et le relais mixte simple. Il n\u2019y a qu\u2019aux Jeux olympiques qu\u2019il n\u2019y a pas de discipline, le relais mixte simple, qui fait partie des Championnats du monde et \u00e9galement de la Coupe du monde.<\/p>\n<h3>Qu\u2019est-ce qui fait partie de l\u2019\u00e9quipement de biathlon ?<\/h3>\n<p>L\u2019\u00e9quipement d\u2019un biathl\u00e8te comprend de nombreux objets sp\u00e9cifiques : les biathl\u00e8tes ont besoin de v\u00eatements adapt\u00e9s, de lunettes de sport, de skis de fond, de chaussures de ski de fond et de b\u00e2tons de ski de fond. Pour le tir, les athl\u00e8tes ont \u00e9galement besoin d\u2019une carabine et de munitions, ainsi que d\u2019un syst\u00e8me de portage pour pouvoir porter la carabine sur le dos pendant le ski de fond.<\/p>\n<h3>Combien de fois tire-t-on au biathlon ?<\/h3>\n<p>Le nombre de tirs effectu\u00e9s par les biathl\u00e8tes au cours d\u2019une comp\u00e9tition d\u00e9pend de la discipline. En sprint, lors de la qualification pour le super sprint et dans tous les relais, les athl\u00e8tes passent deux fois au stand de tir. Dans toutes les autres disciplines, ils passent quatre fois par le stand de tir. Lorsque les athl\u00e8tes se trouvent au stand de tir, ils doivent atteindre cinq cibles, quelle que soit la discipline.<\/p>\n<h3>Quelle est la dur\u00e9e du tour de p\u00e9nalit\u00e9 en biathlon ?<\/h3>\n<p>Si un athl\u00e8te rate son tir, il doit effectuer un tour de p\u00e9nalit\u00e9 dans presque toutes les disciplines. Celle-ci mesure 150 m ou 75 m pour le super sprint et le relais mixte simple et se trouve \u00e0 proximit\u00e9 imm\u00e9diate du stand de tir. Dans la course individuelle uniquement, la p\u00e9nalit\u00e9 pour un tir manqu\u00e9 n\u2019est pas un tour de p\u00e9nalit\u00e9, mais un temps de p\u00e9nalit\u00e9 d\u2019une minute.<\/p>\n<h3>Quelles sont les comp\u00e9titions de biathlon ?<\/h3>\n<p>Les comp\u00e9titions les plus connues et les plus importantes du biathlon sont les comp\u00e9titions internationales des professionnels. Parmi celles-ci figurent la Coupe du monde de biathlon, les Jeux olympiques d\u2019hiver et les Championnats du monde de biathlon.<\/p>\n<h3>O\u00f9 peut-on s\u2019essayer au biathlon ?<\/h3>\n<p>Dans la plupart des stades de biathlon, les amateurs d\u2019hiver curieux peuvent s\u2019essayer \u00e0 ce sport d\u2019hiver. La plupart du temps, des ateliers de biathlon sont organis\u00e9s pour enseigner aux d\u00e9butants les bases du tir et du ski de fond. Ces ateliers sont notamment propos\u00e9s dans les destinations allemandes de Garmisch-Partenkirchen et Oberhof, \u00e0 Hochfilzen en Autriche et dans la station de ski d\u2019Arosa-Lenzerheide en Suisse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le biathlon est l&rsquo;un des sports d&rsquo;hiver les plus connus et les plus populaires au monde. De nombreux fans d&rsquo;hiver sont fascin\u00e9s par ce sport qui allie de mani\u00e8re si unique endurance et pr\u00e9cision et suivent avec attention les comp\u00e9titions au cours desquelles les athl\u00e8tes se surpassent ann\u00e9e apr\u00e8s ann\u00e9e en r\u00e9alisant des performances exceptionnelles. SnowTrex a rassembl\u00e9 10 faits concernant le biathlon et montre ce qui enthousiasme tant d&rsquo;amateurs d&rsquo;hiver dans ce sport unique.<\/p>\n","protected":false},"author":176,"featured_media":650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[767,766,129,704,768,770,18,199,28,699,256,769,34,701,771,727,700,194],"class_list":["post-642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-top-10","tag-allemagne","tag-alpes-bavaroises","tag-arosa","tag-autriche","tag-engadin","tag-foret-de-thuringe","tag-garmisch-partenkirchen","tag-hochfilzen","tag-lenzerheide","tag-les-grisons","tag-oberhof","tag-pillerseetal","tag-saint-moritz","tag-suisse","tag-thuringe","tag-tyrol","tag-vallee-de-schanfigg","tag-zugspitze"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Biathlon - 10 faits sur les disciplines, l&#039;histoire, l&#039;\u00e9quipement &amp; Co<\/title>\n<meta name=\"description\" content=\"Le biathlon est l&#039;un des sports d&#039;hiver les plus populaires. SnowTrex a rassembl\u00e9 en 10 faits les caract\u00e9ristiques de ce sport.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"10 faits sur le biathlon\" \/>\n<meta property=\"og:description\" content=\"Le biathlon est l&#039;un des sports d&#039;hiver les plus connus et les plus populaires au monde. De nombreux fans d&#039;hiver sont fascin\u00e9s par ce sport qui allie de mani\u00e8re si unique endurance et pr\u00e9cision et suivent avec attention les comp\u00e9titions au cours desquelles les athl\u00e8tes se surpassent ann\u00e9e apr\u00e8s ann\u00e9e en r\u00e9alisant des performances exceptionnelles. SnowTrex a rassembl\u00e9 10 faits concernant le biathlon et montre ce qui enthousiasme tant d&#039;amateurs d&#039;hiver dans ce sport unique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/\" \/>\n<meta property=\"og:site_name\" content=\"SnowTrex Ski Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SnowTrex.de\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/snowtrex\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-12T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T12:54:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SnowTrex\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"SnowTrex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/top-10\\\/biathlon\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/top-10\\\/biathlon\\\/\"},\"author\":{\"name\":\"SnowTrex\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#\\\/schema\\\/person\\\/44788d5521abaf7587d53e11859fb827\"},\"headline\":\"10 faits sur le biathlon\",\"datePublished\":\"2023-12-12T00:00:00+00:00\",\"dateModified\":\"2025-06-26T12:54:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/top-10\\\/biathlon\\\/\"},\"wordCount\":3834,\"publisher\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#organization\"},\"image\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/top-10\\\/biathlon\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/files\\\/2023\\\/02\\\/RS21529_shutterstock_1244325379-hsc.jpg\",\"keywords\":[\"Allemagne\",\"Alpes bavaroises\",\"Arosa\",\"Autriche\",\"Engadin\",\"For\u00eat de Thuringe\",\"Garmisch-Partenkirchen\",\"Hochfilzen\",\"Lenzerheide\",\"Les Grisons\",\"Oberhof\",\"Pillerseetal\",\"Saint-Moritz\",\"Suisse\",\"Thuringe\",\"Tyrol\",\"Vall\u00e9e de Schanfigg\",\"Zugspitze\"],\"articleSection\":[\"Top 10\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/top-10\\\/biathlon\\\/\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/top-10\\\/biathlon\\\/\",\"name\":\"Biathlon - 10 faits sur les disciplines, l'histoire, l'\u00e9quipement & Co\",\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/top-10\\\/biathlon\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/top-10\\\/biathlon\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/files\\\/2023\\\/02\\\/RS21529_shutterstock_1244325379-hsc.jpg\",\"datePublished\":\"2023-12-12T00:00:00+00:00\",\"dateModified\":\"2025-06-26T12:54:02+00:00\",\"description\":\"Le biathlon est l'un des sports d'hiver les plus populaires. SnowTrex a rassembl\u00e9 en 10 faits les caract\u00e9ristiques de ce sport.\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/top-10\\\/biathlon\\\/#primaryimage\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/files\\\/2023\\\/02\\\/RS21529_shutterstock_1244325379-hsc.jpg\",\"contentUrl\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/files\\\/2023\\\/02\\\/RS21529_shutterstock_1244325379-hsc.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Quelle: Shutterstock (Standard Lizenz); Frei (Web, Print, SocialMedia) RED+ \u00a9\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#website\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/\",\"name\":\"SnowTrex Ski Magazine\",\"description\":\"Tout sur le ski, le snowboard et les vacances d&#039;hiver !\",\"publisher\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#organization\",\"name\":\"TravelTrex GmbH\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/files\\\/2025\\\/09\\\/TravelTrex-Logo_RGB_transp.png\",\"contentUrl\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/files\\\/2025\\\/09\\\/TravelTrex-Logo_RGB_transp.png\",\"width\":1080,\"height\":282,\"caption\":\"TravelTrex GmbH\"},\"image\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SnowTrex.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/snowtrex_ski\\\/\"],\"description\":\"Depuis 1999, SnowTrex est le premier voyagiste allemand sp\u00e9cialis\u00e9 dans les vacances au ski. L'entreprise commercialise ses offres en 13 langues et accueille chaque ann\u00e9e plus de 100 000 clients dans des destinations pris\u00e9es telles que l'Autriche, la France, l'Italie, la Suisse et l'Allemagne.\",\"email\":\"info-fr@snowtrex.com\",\"telephone\":\"08 05 22 06 10\",\"legalName\":\"TravelTrex GmbH\",\"foundingDate\":\"1999-07-01\",\"vatID\":\"DE 813 076 768\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#\\\/schema\\\/person\\\/44788d5521abaf7587d53e11859fb827\",\"name\":\"SnowTrex\",\"description\":\"La r\u00e9daction du magazine SnowTrex r\u00e9unit des amateurs de sports d'hiver exp\u00e9riment\u00e9s et des experts en voyages qui mettent leur passion au service d'articles approfondis sur les stations de ski, l'\u00e9quipement et les conseils de voyage. Depuis 1999, SnowTrex est le premier voyagiste allemand sp\u00e9cialis\u00e9 dans les vacances au ski. L'entreprise commercialise ses offres en 13 langues et emm\u00e8ne chaque ann\u00e9e plus de 100 000 clients vers des destinations pris\u00e9es telles que l'Autriche, la France, l'Italie, la Suisse et l'Allemagne.\",\"sameAs\":[\"https:\\\/\\\/www.snowtrex.fr\\\/\",\"https:\\\/\\\/www.facebook.com\\\/snowtrex\\\/\",\"https:\\\/\\\/www.instagram.com\\\/snowtrex_ski\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/SnowTrex\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Biathlon - 10 faits sur les disciplines, l'histoire, l'\u00e9quipement & Co","description":"Le biathlon est l'un des sports d'hiver les plus populaires. SnowTrex a rassembl\u00e9 en 10 faits les caract\u00e9ristiques de ce sport.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/","og_locale":"fr_FR","og_type":"article","og_title":"10 faits sur le biathlon","og_description":"Le biathlon est l'un des sports d'hiver les plus connus et les plus populaires au monde. De nombreux fans d'hiver sont fascin\u00e9s par ce sport qui allie de mani\u00e8re si unique endurance et pr\u00e9cision et suivent avec attention les comp\u00e9titions au cours desquelles les athl\u00e8tes se surpassent ann\u00e9e apr\u00e8s ann\u00e9e en r\u00e9alisant des performances exceptionnelles. SnowTrex a rassembl\u00e9 10 faits concernant le biathlon et montre ce qui enthousiasme tant d'amateurs d'hiver dans ce sport unique.","og_url":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/","og_site_name":"SnowTrex Ski Magazine","article_publisher":"https:\/\/www.facebook.com\/SnowTrex.de\/","article_author":"https:\/\/www.facebook.com\/snowtrex\/","article_published_time":"2023-12-12T00:00:00+00:00","article_modified_time":"2025-06-26T12:54:02+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc.jpg","type":"image\/jpeg"}],"author":"SnowTrex","twitter_misc":{"\u00c9crit par":"SnowTrex","Dur\u00e9e de lecture estim\u00e9e":"23 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/#article","isPartOf":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/"},"author":{"name":"SnowTrex","@id":"https:\/\/www.snowtrex.fr\/magazine\/#\/schema\/person\/44788d5521abaf7587d53e11859fb827"},"headline":"10 faits sur le biathlon","datePublished":"2023-12-12T00:00:00+00:00","dateModified":"2025-06-26T12:54:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/"},"wordCount":3834,"publisher":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/#organization"},"image":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc.jpg","keywords":["Allemagne","Alpes bavaroises","Arosa","Autriche","Engadin","For\u00eat de Thuringe","Garmisch-Partenkirchen","Hochfilzen","Lenzerheide","Les Grisons","Oberhof","Pillerseetal","Saint-Moritz","Suisse","Thuringe","Tyrol","Vall\u00e9e de Schanfigg","Zugspitze"],"articleSection":["Top 10"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/","url":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/","name":"Biathlon - 10 faits sur les disciplines, l'histoire, l'\u00e9quipement & Co","primaryImageOfPage":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/#primaryimage"},"image":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc.jpg","datePublished":"2023-12-12T00:00:00+00:00","dateModified":"2025-06-26T12:54:02+00:00","description":"Le biathlon est l'un des sports d'hiver les plus populaires. SnowTrex a rassembl\u00e9 en 10 faits les caract\u00e9ristiques de ce sport.","inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.snowtrex.fr\/magazine\/top-10\/biathlon\/#primaryimage","url":"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc.jpg","contentUrl":"https:\/\/www.snowtrex.fr\/magazine\/files\/2023\/02\/RS21529_shutterstock_1244325379-hsc.jpg","width":1920,"height":1280,"caption":"Quelle: Shutterstock (Standard Lizenz); Frei (Web, Print, SocialMedia) RED+ \u00a9"},{"@type":"WebSite","@id":"https:\/\/www.snowtrex.fr\/magazine\/#website","url":"https:\/\/www.snowtrex.fr\/magazine\/","name":"SnowTrex Ski Magazine","description":"Tout sur le ski, le snowboard et les vacances d&#039;hiver !","publisher":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/#organization"},"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.snowtrex.fr\/magazine\/#organization","name":"TravelTrex GmbH","url":"https:\/\/www.snowtrex.fr\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.snowtrex.fr\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/www.snowtrex.fr\/magazine\/files\/2025\/09\/TravelTrex-Logo_RGB_transp.png","contentUrl":"https:\/\/www.snowtrex.fr\/magazine\/files\/2025\/09\/TravelTrex-Logo_RGB_transp.png","width":1080,"height":282,"caption":"TravelTrex GmbH"},"image":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SnowTrex.de\/","https:\/\/www.instagram.com\/snowtrex_ski\/"],"description":"Depuis 1999, SnowTrex est le premier voyagiste allemand sp\u00e9cialis\u00e9 dans les vacances au ski. L'entreprise commercialise ses offres en 13 langues et accueille chaque ann\u00e9e plus de 100 000 clients dans des destinations pris\u00e9es telles que l'Autriche, la France, l'Italie, la Suisse et l'Allemagne.","email":"info-fr@snowtrex.com","telephone":"08 05 22 06 10","legalName":"TravelTrex GmbH","foundingDate":"1999-07-01","vatID":"DE 813 076 768","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/www.snowtrex.fr\/magazine\/#\/schema\/person\/44788d5521abaf7587d53e11859fb827","name":"SnowTrex","description":"La r\u00e9daction du magazine SnowTrex r\u00e9unit des amateurs de sports d'hiver exp\u00e9riment\u00e9s et des experts en voyages qui mettent leur passion au service d'articles approfondis sur les stations de ski, l'\u00e9quipement et les conseils de voyage. Depuis 1999, SnowTrex est le premier voyagiste allemand sp\u00e9cialis\u00e9 dans les vacances au ski. L'entreprise commercialise ses offres en 13 langues et emm\u00e8ne chaque ann\u00e9e plus de 100 000 clients vers des destinations pris\u00e9es telles que l'Autriche, la France, l'Italie, la Suisse et l'Allemagne.","sameAs":["https:\/\/www.snowtrex.fr\/","https:\/\/www.facebook.com\/snowtrex\/","https:\/\/www.instagram.com\/snowtrex_ski\/","https:\/\/www.youtube.com\/c\/SnowTrex"]}]}},"wp-worthy-pixel":{"ignored":false,"public":null,"server":null,"url":null},"wp-worthy-type":"normal","_links":{"self":[{"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/posts\/642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/users\/176"}],"replies":[{"embeddable":true,"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/comments?post=642"}],"version-history":[{"count":12,"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/posts\/642\/revisions"}],"predecessor-version":[{"id":57757,"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/posts\/642\/revisions\/57757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/media\/650"}],"wp:attachment":[{"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/media?parent=642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/categories?post=642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/tags?post=642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}