{"id":28,"count":15,"description":"","link":"https:\/\/www.snowtrex.fr\/magazine\/tag\/lenzerheide\/","name":"Lenzerheide","slug":"lenzerheide","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lenzerheide - SnowTrex Ski Magazine<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lenzerheide\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.snowtrex.fr\/magazine\/tag\/lenzerheide\/\" \/>\n<meta property=\"og:site_name\" content=\"SnowTrex Ski Magazine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/tag\\\/lenzerheide\\\/\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/tag\\\/lenzerheide\\\/\",\"name\":\"Lenzerheide - SnowTrex Ski Magazine\",\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#website\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/\",\"name\":\"SnowTrex Ski Magazine\",\"description\":\"Tout sur le ski, le snowboard et les vacances d&#039;hiver !\",\"publisher\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#organization\",\"name\":\"TravelTrex GmbH\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/files\\\/2025\\\/09\\\/TravelTrex-Logo_RGB_transp.png\",\"contentUrl\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/files\\\/2025\\\/09\\\/TravelTrex-Logo_RGB_transp.png\",\"width\":1080,\"height\":282,\"caption\":\"TravelTrex GmbH\"},\"image\":{\"@id\":\"http:\\\/\\\/wp-magazin.snowtrex.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SnowTrex.de\\\/\",\"https:\\\/\\\/www.instagram.com\\\/snowtrex_ski\\\/\"],\"description\":\"Depuis 1999, SnowTrex est le premier voyagiste allemand sp\u00e9cialis\u00e9 dans les vacances au ski. L'entreprise commercialise ses offres en 13 langues et accueille chaque ann\u00e9e plus de 100 000 clients dans des destinations pris\u00e9es telles que l'Autriche, la France, l'Italie, la Suisse et l'Allemagne.\",\"email\":\"info-fr@snowtrex.com\",\"telephone\":\"08 05 22 06 10\",\"legalName\":\"TravelTrex GmbH\",\"foundingDate\":\"1999-07-01\",\"vatID\":\"DE 813 076 768\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lenzerheide - SnowTrex Ski Magazine","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Lenzerheide","og_url":"https:\/\/www.snowtrex.fr\/magazine\/tag\/lenzerheide\/","og_site_name":"SnowTrex Ski Magazine","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.snowtrex.fr\/magazine\/tag\/lenzerheide\/","url":"https:\/\/www.snowtrex.fr\/magazine\/tag\/lenzerheide\/","name":"Lenzerheide - SnowTrex Ski Magazine","inLanguage":"fr-FR"},{"@type":"WebSite","@id":"https:\/\/www.snowtrex.fr\/magazine\/#website","url":"https:\/\/www.snowtrex.fr\/magazine\/","name":"SnowTrex Ski Magazine","description":"Tout sur le ski, le snowboard et les vacances d&#039;hiver !","publisher":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/#organization"},"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.snowtrex.fr\/magazine\/#organization","name":"TravelTrex GmbH","url":"https:\/\/www.snowtrex.fr\/magazine\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.snowtrex.fr\/magazine\/#\/schema\/logo\/image\/","url":"https:\/\/www.snowtrex.fr\/magazine\/files\/2025\/09\/TravelTrex-Logo_RGB_transp.png","contentUrl":"https:\/\/www.snowtrex.fr\/magazine\/files\/2025\/09\/TravelTrex-Logo_RGB_transp.png","width":1080,"height":282,"caption":"TravelTrex GmbH"},"image":{"@id":"https:\/\/www.snowtrex.fr\/magazine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SnowTrex.de\/","https:\/\/www.instagram.com\/snowtrex_ski\/"],"description":"Depuis 1999, SnowTrex est le premier voyagiste allemand sp\u00e9cialis\u00e9 dans les vacances au ski. L'entreprise commercialise ses offres en 13 langues et accueille chaque ann\u00e9e plus de 100 000 clients dans des destinations pris\u00e9es telles que l'Autriche, la France, l'Italie, la Suisse et l'Allemagne.","email":"info-fr@snowtrex.com","telephone":"08 05 22 06 10","legalName":"TravelTrex GmbH","foundingDate":"1999-07-01","vatID":"DE 813 076 768","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"_links":{"self":[{"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/tags\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.snowtrex.fr\/magazine\/wp-json\/wp\/v2\/posts?tags=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}